{"id":1118,"date":"2010-06-07T22:13:14","date_gmt":"2010-06-07T22:13:14","guid":{"rendered":"http:\/\/curbsideclothing.com\/blog\/?p=1118"},"modified":"2010-09-30T17:09:10","modified_gmt":"2010-09-30T17:09:10","slug":"1118","status":"publish","type":"post","link":"http:\/\/curbsideclothing.com\/blog\/2010\/06\/1118\/","title":{"rendered":"New Curbside Videos Page"},"content":{"rendered":"<p><CENTER><\/p>\n<h2><a href=\"http:\/\/curbsideclothing.com\/blog\/?page_id=1039\">New Curbside Videos page<\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>New Curbside Videos page<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/posts\/1118"}],"collection":[{"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/comments?post=1118"}],"version-history":[{"count":5,"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/posts\/1118\/revisions"}],"predecessor-version":[{"id":1219,"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/posts\/1118\/revisions\/1219"}],"wp:attachment":[{"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/media?parent=1118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/categories?post=1118"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/curbsideclothing.com\/blog\/wp-json\/wp\/v2\/tags?post=1118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}